  {"id":28330,"date":"2021-05-07T14:41:39","date_gmt":"2021-05-07T12:41:39","guid":{"rendered":"https:\/\/whatthefrance.org\/?p=28330"},"modified":"2021-05-07T14:49:43","modified_gmt":"2021-05-07T12:49:43","slug":"europe-day-2021-les-artistes-europeens-a-lhonneur","status":"publish","type":"post","link":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/","title":{"rendered":"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&rsquo;honneur"},"content":{"rendered":"<p><span class=\"em-orange\">Ce dimanche 9 mai, c&rsquo;est la <strong>Journ\u00e9e de l&rsquo;Europe<\/strong> ! Organis\u00e9e par l&rsquo;Union europ\u00e9enne pour marquer l&rsquo;anniversaire de la fondation de l&rsquo;actuelle Union europ\u00e9enne, la Journ\u00e9e de l&rsquo;Europe est \u00e9galement l&rsquo;occasion de mettre en lumi\u00e8re certains des talents \u00e9mergents de la sc\u00e8ne musicale europ\u00e9enne. <strong>Deux \u00e9v\u00e9nements auront lieu dimanche : le <a href=\"https:\/\/www.europavox.com\/news\/music-europe-day-2021-dedicated-to-the-music-of-europe\/\" target=\"_blank\" rel=\"noopener\">Music Europe Day <\/a><a href=\"https:\/\/www.europavox.com\/news\/music-europe-day-2021-dedicated-to-the-music-of-europe\/\">produit par Europavox<\/a>, et l&rsquo;<a href=\"https:\/\/liveurope.eu\/europe-day\/\" target=\"_blank\" rel=\"noopener\">Europe Day de Liveurope &amp; EBU<\/a>.<\/strong><\/span><\/p>\n<h3>Le <em>Music Europe Day<\/em> d&rsquo;Europavox<\/h3>\n<p><a href=\"https:\/\/www.facebook.com\/EUROPAVOX\"><img decoding=\"async\" class=\"alignnone wp-image-28101\" src=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png\" alt=\"\" width=\"735\" height=\"735\" srcset=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png 300w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-1024x1024.png 1024w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-150x150.png 150w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-768x768.png 768w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-452x452.png 452w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-348x348.png 348w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-254x254.png 254w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-170x170.png 170w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021.png 1080w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><\/a>Le 9 mai 2020, en remplacement au pied lev\u00e9 de la version physique et festive de la F\u00eate de l\u2019Europe rendue impossible, naissait Music Europe Day \u2013 MED, premi\u00e8re \u00e9dition suivie par pr\u00e8s de 600 000 personnes partout dans le monde.<\/p>\n<p>Apr\u00e8s de longs mois faits de peines, de doutes et aussi d\u2019espoirs, l\u2019envie de revenir \u00e0 la vie est plus forte que jamais. Mais m\u00eame dans cet exil forc\u00e9 des sc\u00e8nes, la cr\u00e9ativit\u00e9 a prosp\u00e9r\u00e9 et progress\u00e9 dans toute l\u2019Europe. Ils seront pr\u00e8s de <strong>quinze groupes ou artistes venus de quinze pays d\u2019Europe<\/strong> pour repr\u00e9senter cet \u00e9lan, cet allant, ce talent. Pour la journ\u00e9e de l\u2019Europe, <strong>de 19h \u00e0 minuit<\/strong>, ils offriront pour une soir\u00e9e sur internet leur singularit\u00e9, leur diversit\u00e9, leur mani\u00e8re unique de m\u00e9langer leurs traditions et la modernit\u00e9 d\u2019un monde plus ouvert, plus libre de ses mouvements.<\/p>\n<p>Pour la seconde \u00e9dition de Music Europe Day, ils ont choisi la vie, le live : loin des chambres et studios o\u00f9 ils ont \u00e9t\u00e9 clo\u00eetr\u00e9s, ils pr\u00e9sentent cette ann\u00e9e leur musique pour de courts concerts, avides d\u2019oxyg\u00e8ne et de libert\u00e9, donn\u00e9s et film\u00e9s en ext\u00e9rieur. Dans des lieux qui respirent, symboles de la diversit\u00e9 des territoires qui composent notre espace commun : rooftops de grandes villes et placettes de villages, clairi\u00e8res de for\u00eats et plages de bords de mers&#8230; Les artistes inspirent aussi, lors d&rsquo;entretiens personnels et dr\u00f4les sur leur passion pour la musique, leurs d\u00e9sirs sur le futur de l\u2019Europe, \u00e0 l\u2019heure o\u00f9 s\u2019ouvre un grand d\u00e9bat citoyen sur son avenir.<\/p>\n<p>Parmi les 15 artistes qui seront pr\u00e9sents \u00e0 l&rsquo;\u00e9v\u00e9nement, <a href=\"https:\/\/www.facebook.com\/davidwaltersplay\/\" target=\"_blank\" rel=\"noopener\"><strong>David Walters<\/strong><\/a> repr\u00e9sentera la France, et le duo franco-arm\u00e9nien <a href=\"https:\/\/www.facebook.com\/ladanivayaman\/\" target=\"_blank\" rel=\"noopener\"><strong>Ladaniva<\/strong><\/a>, produit par le producteur fran\u00e7ais <a href=\"https:\/\/www.facebook.com\/DionysiacTourBookingAgency\" target=\"_blank\" rel=\"noopener\">Dionysiac Tour<\/a>, sera \u00e9galement \u00e0 voir en concert.<\/p>\n<p>Le reste du Line-Up inclut : <a href=\"https:\/\/www.facebook.com\/BalkanTaksim\" target=\"_blank\" rel=\"noopener\">Balkan Taksim<\/a> (RO), <a href=\"https:\/\/www.facebook.com\/daithimusic\" target=\"_blank\" rel=\"noopener\">Daith\u00ed<\/a> (IR), <a href=\"https:\/\/www.facebook.com\/garbanotas\" target=\"_blank\" rel=\"noopener\">Garbanotas<\/a> (LT), <a href=\"https:\/\/www.facebook.com\/GirlsInHawaii\" target=\"_blank\" rel=\"noopener\">Girls in Hawaii<\/a> (BE), <a href=\"https:\/\/www.facebook.com\/kidsimius\" target=\"_blank\" rel=\"noopener\">Kid Simius<\/a> (DE), <a href=\"https:\/\/www.facebook.com\/bandlor\" target=\"_blank\" rel=\"noopener\">Lor<\/a> (PL), <a href=\"https:\/\/www.facebook.com\/lydmor\/\" target=\"_blank\" rel=\"noopener\">Lydmor<\/a> (DK), <a href=\"https:\/\/www.facebook.com\/myuglyclementine?__tn__=%3C\" target=\"_blank\" rel=\"noopener\">My Ugly Clementine<\/a> (AT), <a href=\"https:\/\/www.facebook.com\/nemanja.hr\" target=\"_blank\" rel=\"noopener\">nemanja<\/a> (HR), <a href=\"https:\/\/www.facebook.com\/nennyoficial\" target=\"_blank\" rel=\"noopener\">Nenny<\/a> (PT).<\/p>\n<p>Vous pouvez suivre cet \u00e9v\u00e9nement sur <b><a href=\"https:\/\/www.facebook.com\/whatthefrance\" target=\"_blank\" rel=\"noopener\">notre page Facebook.<\/a>\u00a0<\/b><\/p>\n<h3>L&rsquo;<em>Europe Day<\/em> de Liveurope &amp; EBU<\/h3>\n<p><a href=\"http:\/\/www.europeday.live\/\"><img decoding=\"async\" class=\"alignnone wp-image-28106\" src=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-300x300.jpg\" alt=\"\" width=\"752\" height=\"752\" srcset=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-300x300.jpg 300w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-1024x1024.jpg 1024w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-150x150.jpg 150w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-768x768.jpg 768w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-1536x1536.jpg 1536w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-2048x2048.jpg 2048w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-452x452.jpg 452w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-348x348.jpg 348w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-254x254.jpg 254w, https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Static-Line-up-square-Europe-day-170x170.jpg 170w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/><\/a>Pour la septi\u00e8me ann\u00e9e cons\u00e9cutive, <a href=\"https:\/\/liveurope.eu\/\" target=\"_blank\" rel=\"noopener\"><strong>Liveurope<\/strong><\/a> c\u00e9l\u00e9brera la Journ\u00e9e de l&rsquo;Europe en faisant ce qu&rsquo;elle sait faire le mieux : mettre en lumi\u00e8re les nouveaux talents europ\u00e9ens. Et, pour l&rsquo;\u00e9dition de cette ann\u00e9e, ils b\u00e9n\u00e9ficient du soutien des stations de radio publiques de l&rsquo;Union europ\u00e9enne de radiodiffusion pour aider les artistes \u00e0 toucher un public encore plus large.<\/p>\n<p>Chacun des 15 sites Liveurope participants a enregistr\u00e9 un <strong>mini-showcase exclusif<\/strong> avec un artiste local prometteur qui sera diffus\u00e9 par un certain nombre de radios en Europe et dans le monde, \u00e0 partir de la semaine de la Journ\u00e9e de l&rsquo;Europe. Certaines de ces radios pr\u00e9parent \u00e9galement des \u00e9missions tr\u00e8s sp\u00e9ciales qui vous feront d\u00e9couvrir les coulisses de cette initiative, avec notamment des interviews des artistes et des lieux.<\/p>\n<p>Cette campagne est soutenue par le programme <a href=\"https:\/\/ec.europa.eu\/programmes\/creative-europe\/node_fr\"><strong>Europe cr\u00e9ative<\/strong><\/a> de la Commission europ\u00e9enne et b\u00e9n\u00e9ficie du soutien officiel de la pr\u00e9sidence portugaise du Conseil de l&rsquo;Union europ\u00e9enne et du groupe d&rsquo;amiti\u00e9 des cr\u00e9ateurs culturels au Parlement europ\u00e9en.<\/p>\n<p>Concernant les artistes, c&rsquo;est le groupe fran\u00e7ais <a href=\"https:\/\/www.facebook.com\/pogocarcrashcontrol\/\" target=\"_blank\" rel=\"noopener\"><strong>Pogo Car Crash Control<\/strong><\/a> qui repr\u00e9sentera la France lors du Europe Day de Liveurope !<\/p>\n<p>La programmation compl\u00e8te de la journ\u00e9e comprend <a href=\"https:\/\/www.facebook.com\/agata.karczewska.folksinger\" target=\"_blank\" rel=\"noopener\">Agata Karczewska<\/a> (PL), <a href=\"https:\/\/www.facebook.com\/altingunband\/\" target=\"_blank\" rel=\"noopener\">Alt\u0131n G\u00fcn<\/a> (NL), <a href=\"https:\/\/www.facebook.com\/Amelie-Siba-114392080289319\" target=\"_blank\" rel=\"noopener\">Amelie Siba<\/a> (CZ), <a href=\"https:\/\/www.facebook.com\/belaumusic\" target=\"_blank\" rel=\"noopener\">Belau<\/a> (HU), <a href=\"https:\/\/www.facebook.com\/davidnumwamimusic\" target=\"_blank\" rel=\"noopener\">David Numwami<\/a> (BE), <a href=\"https:\/\/www.facebook.com\/emmabradleymusic\" target=\"_blank\" rel=\"noopener\">Emma Bradley<\/a> (UK), <a href=\"https:\/\/www.facebook.com\/flycktmusic\/\" target=\"_blank\" rel=\"noopener\">FLYCKT<\/a> (SE), <a href=\"https:\/\/www.facebook.com\/francisofdelirium\/\" target=\"_blank\" rel=\"noopener\">Francis of Delirium<\/a> (LU), <a href=\"https:\/\/www.facebook.com\/greta.geschenk\" target=\"_blank\" rel=\"noopener\">Greta<\/a> (DK), <a href=\"https:\/\/www.facebook.com\/moglimoglimogli\" target=\"_blank\" rel=\"noopener\">Moglii<\/a> (DE), <a href=\"https:\/\/www.facebook.com\/pompokounofficial\/?__tn__=%3C\" target=\"_blank\" rel=\"noopener\">Pom Poko<\/a> (NO), <a href=\"https:\/\/www.facebook.com\/SelmaUamusse\" target=\"_blank\" rel=\"noopener\">Selma Uamusse<\/a> (PT), <a href=\"https:\/\/www.facebook.com\/thisishomas\/\" target=\"_blank\" rel=\"noopener\">Stay Homas<\/a> (ES) et <a href=\"https:\/\/www.facebook.com\/zalagasper\" target=\"_blank\" rel=\"noopener\">Zalagasper<\/a> (SI).<\/p>\n<p>Toutes les vid\u00e9os des showcases pourront \u00e9galement \u00eatre visionn\u00e9es sur le site web du <a href=\"http:\/\/www.europeday.live\/\" target=\"_blank\" rel=\"noopener\"><strong>Europe Day de Liveurope<\/strong><\/a> \u00e0 partir du 9 mai.<\/p>\n<div class=\"playListBloc singleBloc\"><div class=\"playListBloc-wrap\">    <div class=\"thumbnail\"><img data-src=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2018\/11\/WTF-Pochettes_hits_monde_2-254x254.jpg\" class=\"lazyload\" alt=\"WTF&#8212;Pochettes_hits_monde_2\" \/>    <\/div>    <div class=\"infos\">        <span class=\"tag\">Charts &amp; News<\/span>        <h2>French Hits Worldwide<\/h2>        <span class=\"separator\"><\/span>       <span class=\"desc\">The biggest made in France hits topping the charts around the world. <\/span><div class=\"share flex flexAlignCenter \">\t<span class=\"label\">Partager<\/span>\t<a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/whatthefrance.org\/fr\/playlists\/french-hits-worldwide\/\" class=\"facebook\" target=\"_blank\" rel=\"noreferrer\">Facebook<\/a>\t<a href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/whatthefrance.org\/fr\/playlists\/french-hits-worldwide\/&text=French+Hits+Worldwide&hashtags=WTF\" class=\"twitter\" target=\"_blank\" rel=\"noreferrer\">Twitter<\/a>\t<a href=\"mailto:?subject=What%20the%20France%20%3A%20French%20Hits%20Worldwide&body=https:\/\/whatthefrance.org\/fr\/playlists\/french-hits-worldwide\/\" class=\"mail\" target=\"_blank\" rel=\"noreferrer\">Email<\/a><\/div>        <a href=\"#\" class=\"btn btnPlaylist orange playlist-click\" data-id=\"867\">            <svg version=\"1.1\" x=\"0px\" y=\"0px\" width=\"40px\" height=\"40px\" viewBox=\"0 0 213.7 213.7\" enable-background=\"new 0 0 213.7 213.7\" xml:space=\"preserve\">                <polygon class=\"triangle\" fill=\"none\" stroke-width=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" points=\"\n            73.5,62.5 148.5,105.8 73.5,149.1 \"\/>                <circle class=\"circle\" fill=\"none\"  stroke-width=\"8\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" cx=\"106.8\" cy=\"106.8\" r=\"103.3\"\/>                <circle class=\"circle-white\" fill=\"none\"  stroke-width=\"8\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" cx=\"106.8\" cy=\"106.8\" r=\"103.3\"\/>            <\/svg>Ecouter        <\/a>    <\/div>  <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche 9 mai, c&rsquo;est la Journ\u00e9e de l&rsquo;Europe ! Organis\u00e9e par l&rsquo;Union europ\u00e9enne pour marquer l&rsquo;anniversaire de la fondation de l&rsquo;actuelle Union europ\u00e9enne, la Journ\u00e9e de l&rsquo;Europe est \u00e9galement l&rsquo;occasion de mettre en lumi\u00e8re certains des talents \u00e9mergents de la sc\u00e8ne musicale europ\u00e9enne. Deux \u00e9v\u00e9nements auront lieu dimanche : le Music Europe Day produit [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[213],"tags":[323,327,351],"class_list":["post-28330","post","type-post","status-publish","format-standard","hentry","category-event-fr","tag-electronic-fr","tag-folk-fr","tag-rock-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&#039;honneur - What the France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&#039;honneur - What the France\" \/>\n<meta property=\"og:description\" content=\"Ce dimanche 9 mai, c&rsquo;est la Journ\u00e9e de l&rsquo;Europe ! Organis\u00e9e par l&rsquo;Union europ\u00e9enne pour marquer l&rsquo;anniversaire de la fondation de l&rsquo;actuelle Union europ\u00e9enne, la Journ\u00e9e de l&rsquo;Europe est \u00e9galement l&rsquo;occasion de mettre en lumi\u00e8re certains des talents \u00e9mergents de la sc\u00e8ne musicale europ\u00e9enne. Deux \u00e9v\u00e9nements auront lieu dimanche : le Music Europe Day produit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/\" \/>\n<meta property=\"og:site_name\" content=\"What the France\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T12:41:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T12:49:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/europe_day_what_the_france.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/><meta property=\"og:image\" content=\"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png\" \/>\n<meta name=\"author\" content=\"Stagiaire 1 Berlin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stagiaire 1 Berlin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/\"},\"author\":{\"name\":\"Stagiaire 1 Berlin\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#\\\/schema\\\/person\\\/a72915ae82250c292822ed109081970a\"},\"headline\":\"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&rsquo;honneur\",\"datePublished\":\"2021-05-07T12:41:39+00:00\",\"dateModified\":\"2021-05-07T12:49:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/\"},\"wordCount\":749,\"publisher\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatthefrance.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Square-Music-Europe-Day-2021-300x300.png\",\"keywords\":[\"Electronic\",\"Folk\",\"Rock\"],\"articleSection\":[\"Event\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/\",\"url\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/\",\"name\":\"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l'honneur - What the France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatthefrance.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Square-Music-Europe-Day-2021-300x300.png\",\"datePublished\":\"2021-05-07T12:41:39+00:00\",\"dateModified\":\"2021-05-07T12:49:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whatthefrance.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Square-Music-Europe-Day-2021-300x300.png\",\"contentUrl\":\"https:\\\/\\\/whatthefrance.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Square-Music-Europe-Day-2021-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/europe-day-2021-les-artistes-europeens-a-lhonneur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&rsquo;honneur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/\",\"name\":\"What the France\",\"description\":\"The finest music made in France !\",\"publisher\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#organization\",\"name\":\"What The France\",\"url\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whatthefrance.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/44688719_2251580388408837_694180218134331392_n-e1577679609190.png\",\"contentUrl\":\"https:\\\/\\\/whatthefrance.org\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/44688719_2251580388408837_694180218134331392_n-e1577679609190.png\",\"width\":200,\"height\":200,\"caption\":\"What The France\"},\"image\":{\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/whatthefrance.org\\\/fr\\\/#\\\/schema\\\/person\\\/a72915ae82250c292822ed109081970a\",\"name\":\"Stagiaire 1 Berlin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfeb8d88ae59b52c2ef8ba0be98ebede06bf72bd97d535142490a9391ffa2c33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfeb8d88ae59b52c2ef8ba0be98ebede06bf72bd97d535142490a9391ffa2c33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfeb8d88ae59b52c2ef8ba0be98ebede06bf72bd97d535142490a9391ffa2c33?s=96&d=mm&r=g\",\"caption\":\"Stagiaire 1 Berlin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l'honneur - What the France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/","og_locale":"fr_FR","og_type":"article","og_title":"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l'honneur - What the France","og_description":"Ce dimanche 9 mai, c&rsquo;est la Journ\u00e9e de l&rsquo;Europe ! Organis\u00e9e par l&rsquo;Union europ\u00e9enne pour marquer l&rsquo;anniversaire de la fondation de l&rsquo;actuelle Union europ\u00e9enne, la Journ\u00e9e de l&rsquo;Europe est \u00e9galement l&rsquo;occasion de mettre en lumi\u00e8re certains des talents \u00e9mergents de la sc\u00e8ne musicale europ\u00e9enne. Deux \u00e9v\u00e9nements auront lieu dimanche : le Music Europe Day produit [&hellip;]","og_url":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/","og_site_name":"What the France","article_published_time":"2021-05-07T12:41:39+00:00","article_modified_time":"2021-05-07T12:49:43+00:00","og_image":[{"url":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/europe_day_what_the_france.png","height":452,"width":1084,"type":""},{"url":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png","type":"","width":"","height":""}],"author":"Stagiaire 1 Berlin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Stagiaire 1 Berlin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#article","isPartOf":{"@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/"},"author":{"name":"Stagiaire 1 Berlin","@id":"https:\/\/whatthefrance.org\/fr\/#\/schema\/person\/a72915ae82250c292822ed109081970a"},"headline":"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&rsquo;honneur","datePublished":"2021-05-07T12:41:39+00:00","dateModified":"2021-05-07T12:49:43+00:00","mainEntityOfPage":{"@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/"},"wordCount":749,"publisher":{"@id":"https:\/\/whatthefrance.org\/fr\/#organization"},"image":{"@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#primaryimage"},"thumbnailUrl":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png","keywords":["Electronic","Folk","Rock"],"articleSection":["Event"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/","url":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/","name":"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l'honneur - What the France","isPartOf":{"@id":"https:\/\/whatthefrance.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#primaryimage"},"image":{"@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#primaryimage"},"thumbnailUrl":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png","datePublished":"2021-05-07T12:41:39+00:00","dateModified":"2021-05-07T12:49:43+00:00","breadcrumb":{"@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#primaryimage","url":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png","contentUrl":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2021\/04\/Square-Music-Europe-Day-2021-300x300.png"},{"@type":"BreadcrumbList","@id":"https:\/\/whatthefrance.org\/fr\/europe-day-2021-les-artistes-europeens-a-lhonneur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whatthefrance.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Europe Day 2021 | Les artistes europ\u00e9ens \u00e0 l&rsquo;honneur"}]},{"@type":"WebSite","@id":"https:\/\/whatthefrance.org\/fr\/#website","url":"https:\/\/whatthefrance.org\/fr\/","name":"What the France","description":"The finest music made in France !","publisher":{"@id":"https:\/\/whatthefrance.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whatthefrance.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/whatthefrance.org\/fr\/#organization","name":"What The France","url":"https:\/\/whatthefrance.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/whatthefrance.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2019\/12\/44688719_2251580388408837_694180218134331392_n-e1577679609190.png","contentUrl":"https:\/\/whatthefrance.org\/wp-content\/uploads\/2019\/12\/44688719_2251580388408837_694180218134331392_n-e1577679609190.png","width":200,"height":200,"caption":"What The France"},"image":{"@id":"https:\/\/whatthefrance.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/whatthefrance.org\/fr\/#\/schema\/person\/a72915ae82250c292822ed109081970a","name":"Stagiaire 1 Berlin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/dfeb8d88ae59b52c2ef8ba0be98ebede06bf72bd97d535142490a9391ffa2c33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dfeb8d88ae59b52c2ef8ba0be98ebede06bf72bd97d535142490a9391ffa2c33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfeb8d88ae59b52c2ef8ba0be98ebede06bf72bd97d535142490a9391ffa2c33?s=96&d=mm&r=g","caption":"Stagiaire 1 Berlin"}}]}},"_links":{"self":[{"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/posts\/28330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/comments?post=28330"}],"version-history":[{"count":12,"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/posts\/28330\/revisions"}],"predecessor-version":[{"id":28349,"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/posts\/28330\/revisions\/28349"}],"wp:attachment":[{"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/media?parent=28330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/categories?post=28330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whatthefrance.org\/fr\/wp-json\/wp\/v2\/tags?post=28330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}